{"id":52655,"date":"2026-01-16T10:43:43","date_gmt":"2026-01-16T13:43:43","guid":{"rendered":"https:\/\/smartcherry.cl\/?p=52655"},"modified":"2026-01-16T10:45:57","modified_gmt":"2026-01-16T13:45:57","slug":"cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada","status":"publish","type":"post","link":"https:\/\/smartcherry.cl\/en\/noticias\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\/","title":{"rendered":"Cerezas chilenas en China: Coordinaci\u00f3n, calidad y estrategia como aspectos claves de la temporada"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong><em>En pleno desarrollo de la temporada 2025\/26, Guangzhou fue escenario, el pasado 14 de enero, de la primera edici\u00f3n del China Cherry Mid-Season Summit, una instancia dise\u00f1ada para entregar informaci\u00f3n directa y an\u00e1lisis en tiempo real a la industria de la cereza, justo antes del per\u00edodo comercial m\u00e1s relevante del a\u00f1o.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento fue organizado por Yentzen Group, cofundador junto a Smartcherry de CherryTech, y permiti\u00f3 a exportadores y productores chilenos contrastar su visi\u00f3n con importadores y retailers chinos, generando un diagn\u00f3stico compartido sobre ventas, log\u00edstica, calidad y comportamiento del consumidor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta coordinaci\u00f3n temprana se volvi\u00f3 especialmente relevante en una temporada marcada por altos vol\u00famenes, exigencias log\u00edsticas y una competencia creciente dentro de la categor\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cifras expuestas durante la jornada confirmaron la importancia de la cereza dentro del mercado chino de frutas importadas, as\u00ed como el rol preponderante de Chile como principal proveedor. Sin embargo, tambi\u00e9n qued\u00f3 en evidencia que el liderazgo ya no garantiza resultados si no va acompa\u00f1ado de una estrategia m\u00e1s afinada.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"585\" src=\"https:\/\/smartcherry.cl\/wp-content\/uploads\/2026\/01\/Claudia-Soler-China-Cherry-1024x585.jpg\" alt=\"\" class=\"wp-image-52658\" srcset=\"https:\/\/smartcherry.cl\/wp-content\/uploads\/2026\/01\/Claudia-Soler-China-Cherry-1024x585.jpg 1024w, https:\/\/smartcherry.cl\/wp-content\/uploads\/2026\/01\/Claudia-Soler-China-Cherry-300x171.jpg 300w, https:\/\/smartcherry.cl\/wp-content\/uploads\/2026\/01\/Claudia-Soler-China-Cherry-768x439.jpg 768w, https:\/\/smartcherry.cl\/wp-content\/uploads\/2026\/01\/Claudia-Soler-China-Cherry-18x10.jpg 18w, https:\/\/smartcherry.cl\/wp-content\/uploads\/2026\/01\/Claudia-Soler-China-Cherry.jpg 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><strong>Claudia Soler, directora ejecutiva del Comit\u00e9 de Cerezas de Frutas de Chile.<\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el Comit\u00e9 de Cerezas de Frutas de Chile se subray\u00f3 que el consumidor chino ha evolucionado: hoy es m\u00e1s sensible a la calidad, m\u00e1s informado y menos tolerante a inconsistencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este cambio obliga a la industria a proteger el car\u00e1cter premium del producto, cuidando no s\u00f3lo el precio, sino tambi\u00e9n la experiencia completa que recibe el consumidor final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los an\u00e1lisis de mercado profundizaron en los riesgos de una oferta temprana excesiva y en la necesidad de equilibrar volumen y calidad. La conclusi\u00f3n fue transversal: la sostenibilidad futura de la cereza chilena en China depender\u00e1 de una gesti\u00f3n m\u00e1s estrat\u00e9gica, profesional y coordinada, capaz de adaptarse a una nueva normalidad del mercado.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"585\" src=\"https:\/\/smartcherry.cl\/wp-content\/uploads\/2026\/01\/China-Cherry-Mid-Season-Summit-2-1024x585.jpg\" alt=\"\" class=\"wp-image-52659\" srcset=\"https:\/\/smartcherry.cl\/wp-content\/uploads\/2026\/01\/China-Cherry-Mid-Season-Summit-2-1024x585.jpg 1024w, https:\/\/smartcherry.cl\/wp-content\/uploads\/2026\/01\/China-Cherry-Mid-Season-Summit-2-300x171.jpg 300w, https:\/\/smartcherry.cl\/wp-content\/uploads\/2026\/01\/China-Cherry-Mid-Season-Summit-2-768x439.jpg 768w, https:\/\/smartcherry.cl\/wp-content\/uploads\/2026\/01\/China-Cherry-Mid-Season-Summit-2-18x10.jpg 18w, https:\/\/smartcherry.cl\/wp-content\/uploads\/2026\/01\/China-Cherry-Mid-Season-Summit-2.jpg 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><strong>China Cherry Mid-Season Summit 2026 se realiz\u00f3 en la ciudad de Guangzhou.<\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">De esta forma, el China Cherry Mid-Season Summit se convirti\u00f3 en el punto de inflexi\u00f3n de la temporada, ante un mercado chino m\u00e1s exigente y que proyecta desaf\u00edos inmediatos en materia de calidad, log\u00edstica y posicionamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La primera versi\u00f3n de este encuentro es, adem\u00e1s, la antesala del Global Cherry Summit, tambi\u00e9n organizado por Yentzen Group, que se efectuar\u00e1 en el mes abril en nuestro pa\u00eds, que entregar\u00e1 un an\u00e1lisis comercial de la temporada, para luego continuar con CherryTech 2026, el encuentro t\u00e9cnico m\u00e1s importante de la industria cerecera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Smartcherry est\u00e1 muy orgulloso de nuestros socios por los resultados logrados en este evento, que afianza el compromiso por generar m\u00e1s instancias de encuentro y an\u00e1lisis respecto de lo que sucede en la industria de la cereza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ta invitamos a revisar un video resumen del China Cherry Mid-Season Summit 2026.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Cerezas chilenas en China: Coordinaci\u00f3n, calidad y estrategia como aspectos claves de la temporada\" width=\"800\" height=\"600\" src=\"https:\/\/www.youtube.com\/embed\/aKXPgWEa3LI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>El China Cherry Mid-Season Summit reuni\u00f3 en Guangzhou a los principales actores de la cadena para ajustar estrategias frente a un mercado que ya no compite solo en precio, sino en valor y experiencia de consumo.<\/p>","protected":false},"author":273,"featured_media":52656,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[2631,35],"tags":[1750,2313,4421],"category_proveedor":[],"pais":[],"class_list":["post-52655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-noticias","tag-yentzen-group","tag-guangzhou","tag-china-cherry-mid-season-summit"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cerezas chilenas en China: Coordinaci\u00f3n, calidad y estrategia como aspectos claves de la temporada - Smartcherry<\/title>\n<meta name=\"description\" content=\"En pleno desarrollo de la temporada 2025\/26, Guangzhou fue escenario, el pasado 14 de enero, de la primera edici\u00f3n del China Cherry Mid-Season Summit, una instancia dise\u00f1ada para entregar informaci\u00f3n directa y an\u00e1lisis en tiempo real a la industria de la cereza, justo antes del per\u00edodo comercial m\u00e1s relevante del a\u00f1o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smartcherry.cl\/en\/noticias\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cerezas chilenas en China: Coordinaci\u00f3n, calidad y estrategia como aspectos claves de la temporada\" \/>\n<meta property=\"og:description\" content=\"En pleno desarrollo de la temporada 2025\/26, Guangzhou fue escenario, el pasado 14 de enero, de la primera edici\u00f3n del China Cherry Mid-Season Summit, una instancia dise\u00f1ada para entregar informaci\u00f3n directa y an\u00e1lisis en tiempo real a la industria de la cereza, justo antes del per\u00edodo comercial m\u00e1s relevante del a\u00f1o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smartcherry.cl\/en\/noticias\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\/\" \/>\n<meta property=\"og:site_name\" content=\"Smartcherry\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/SmartCherry.cl\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-16T13:43:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-16T13:45:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smartcherry.cl\/wp-content\/uploads\/2026\/01\/China-Cherry-Mid-Season-Summit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Beatriz Parra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SmartCherry_cl\" \/>\n<meta name=\"twitter:site\" content=\"@SmartCherry_cl\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Beatriz Parra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\\\/\"},\"author\":{\"name\":\"Beatriz Parra\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#\\\/schema\\\/person\\\/604ed44370e96b081064b745ca461407\"},\"headline\":\"Cerezas chilenas en China: Coordinaci\u00f3n, calidad y estrategia como aspectos claves de la temporada\",\"datePublished\":\"2026-01-16T13:43:43+00:00\",\"dateModified\":\"2026-01-16T13:45:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\\\/\"},\"wordCount\":495,\"publisher\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/China-Cherry-Mid-Season-Summit.jpg\",\"keywords\":[\"Yentzen Group\",\"Guangzhou\",\"China Cherry Mid-Season Summit\"],\"articleSection\":[\"Eventos\",\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\\\/\",\"url\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\\\/\",\"name\":\"Cerezas chilenas en China: Coordinaci\u00f3n, calidad y estrategia como aspectos claves de la temporada - Smartcherry\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/China-Cherry-Mid-Season-Summit.jpg\",\"datePublished\":\"2026-01-16T13:43:43+00:00\",\"dateModified\":\"2026-01-16T13:45:57+00:00\",\"description\":\"En pleno desarrollo de la temporada 2025\\\/26, Guangzhou fue escenario, el pasado 14 de enero, de la primera edici\u00f3n del China Cherry Mid-Season Summit, una instancia dise\u00f1ada para entregar informaci\u00f3n directa y an\u00e1lisis en tiempo real a la industria de la cereza, justo antes del per\u00edodo comercial m\u00e1s relevante del a\u00f1o.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/China-Cherry-Mid-Season-Summit.jpg\",\"contentUrl\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/China-Cherry-Mid-Season-Summit.jpg\",\"width\":1400,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smartcherry.cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/smartcherry.cl\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cerezas chilenas en China: Coordinaci\u00f3n, calidad y estrategia como aspectos claves de la temporada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#website\",\"url\":\"https:\\\/\\\/smartcherry.cl\\\/\",\"name\":\"Smartcherry\",\"description\":\"Sitio de Smartcherry\",\"publisher\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smartcherry.cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#organization\",\"name\":\"SmartCherry\",\"url\":\"https:\\\/\\\/smartcherry.cl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo_smartcherry.png\",\"contentUrl\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo_smartcherry.png\",\"width\":411,\"height\":84,\"caption\":\"SmartCherry\"},\"image\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/SmartCherry.cl\\\/\",\"https:\\\/\\\/x.com\\\/SmartCherry_cl\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/smartcherry\\\/\",\"https:\\\/\\\/www.instagram.com\\\/smartcherry_cl\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCe007LfgFFnntDgCcqICbPQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#\\\/schema\\\/person\\\/604ed44370e96b081064b745ca461407\",\"name\":\"Beatriz Parra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/POST-96x96.png\",\"url\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/POST-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/POST-96x96.png\",\"caption\":\"Beatriz Parra\"},\"url\":\"https:\\\/\\\/smartcherry.cl\\\/en\\\/author\\\/bparra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cerezas chilenas en China: Coordinaci\u00f3n, calidad y estrategia como aspectos claves de la temporada - Smartcherry","description":"En pleno desarrollo de la temporada 2025\/26, Guangzhou fue escenario, el pasado 14 de enero, de la primera edici\u00f3n del China Cherry Mid-Season Summit, una instancia dise\u00f1ada para entregar informaci\u00f3n directa y an\u00e1lisis en tiempo real a la industria de la cereza, justo antes del per\u00edodo comercial m\u00e1s relevante del a\u00f1o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smartcherry.cl\/en\/noticias\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\/","og_locale":"en_US","og_type":"article","og_title":"Cerezas chilenas en China: Coordinaci\u00f3n, calidad y estrategia como aspectos claves de la temporada","og_description":"En pleno desarrollo de la temporada 2025\/26, Guangzhou fue escenario, el pasado 14 de enero, de la primera edici\u00f3n del China Cherry Mid-Season Summit, una instancia dise\u00f1ada para entregar informaci\u00f3n directa y an\u00e1lisis en tiempo real a la industria de la cereza, justo antes del per\u00edodo comercial m\u00e1s relevante del a\u00f1o.","og_url":"https:\/\/smartcherry.cl\/en\/noticias\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\/","og_site_name":"Smartcherry","article_publisher":"https:\/\/web.facebook.com\/SmartCherry.cl\/","article_published_time":"2026-01-16T13:43:43+00:00","article_modified_time":"2026-01-16T13:45:57+00:00","og_image":[{"width":1400,"height":800,"url":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2026\/01\/China-Cherry-Mid-Season-Summit.jpg","type":"image\/jpeg"}],"author":"Beatriz Parra","twitter_card":"summary_large_image","twitter_creator":"@SmartCherry_cl","twitter_site":"@SmartCherry_cl","twitter_misc":{"Written by":"Beatriz Parra","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smartcherry.cl\/noticias\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\/#article","isPartOf":{"@id":"https:\/\/smartcherry.cl\/noticias\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\/"},"author":{"name":"Beatriz Parra","@id":"https:\/\/smartcherry.cl\/#\/schema\/person\/604ed44370e96b081064b745ca461407"},"headline":"Cerezas chilenas en China: Coordinaci\u00f3n, calidad y estrategia como aspectos claves de la temporada","datePublished":"2026-01-16T13:43:43+00:00","dateModified":"2026-01-16T13:45:57+00:00","mainEntityOfPage":{"@id":"https:\/\/smartcherry.cl\/noticias\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\/"},"wordCount":495,"publisher":{"@id":"https:\/\/smartcherry.cl\/#organization"},"image":{"@id":"https:\/\/smartcherry.cl\/noticias\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\/#primaryimage"},"thumbnailUrl":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2026\/01\/China-Cherry-Mid-Season-Summit.jpg","keywords":["Yentzen Group","Guangzhou","China Cherry Mid-Season Summit"],"articleSection":["Eventos","Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/smartcherry.cl\/noticias\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\/","url":"https:\/\/smartcherry.cl\/noticias\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\/","name":"Cerezas chilenas en China: Coordinaci\u00f3n, calidad y estrategia como aspectos claves de la temporada - Smartcherry","isPartOf":{"@id":"https:\/\/smartcherry.cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smartcherry.cl\/noticias\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\/#primaryimage"},"image":{"@id":"https:\/\/smartcherry.cl\/noticias\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\/#primaryimage"},"thumbnailUrl":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2026\/01\/China-Cherry-Mid-Season-Summit.jpg","datePublished":"2026-01-16T13:43:43+00:00","dateModified":"2026-01-16T13:45:57+00:00","description":"En pleno desarrollo de la temporada 2025\/26, Guangzhou fue escenario, el pasado 14 de enero, de la primera edici\u00f3n del China Cherry Mid-Season Summit, una instancia dise\u00f1ada para entregar informaci\u00f3n directa y an\u00e1lisis en tiempo real a la industria de la cereza, justo antes del per\u00edodo comercial m\u00e1s relevante del a\u00f1o.","breadcrumb":{"@id":"https:\/\/smartcherry.cl\/noticias\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smartcherry.cl\/noticias\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/smartcherry.cl\/noticias\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\/#primaryimage","url":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2026\/01\/China-Cherry-Mid-Season-Summit.jpg","contentUrl":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2026\/01\/China-Cherry-Mid-Season-Summit.jpg","width":1400,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/smartcherry.cl\/noticias\/cerezas-chilenas-en-china-coordinacion-calidad-y-estrategia-como-aspectos-claves-de-la-temporada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smartcherry.cl\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/smartcherry.cl\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Cerezas chilenas en China: Coordinaci\u00f3n, calidad y estrategia como aspectos claves de la temporada"}]},{"@type":"WebSite","@id":"https:\/\/smartcherry.cl\/#website","url":"https:\/\/smartcherry.cl\/","name":"Smartcherry","description":"Smartcherry Site","publisher":{"@id":"https:\/\/smartcherry.cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smartcherry.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/smartcherry.cl\/#organization","name":"SmartCherry","url":"https:\/\/smartcherry.cl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/smartcherry.cl\/#\/schema\/logo\/image\/","url":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2022\/02\/logo_smartcherry.png","contentUrl":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2022\/02\/logo_smartcherry.png","width":411,"height":84,"caption":"SmartCherry"},"image":{"@id":"https:\/\/smartcherry.cl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/SmartCherry.cl\/","https:\/\/x.com\/SmartCherry_cl","https:\/\/www.linkedin.com\/company\/smartcherry\/","https:\/\/www.instagram.com\/smartcherry_cl\/","https:\/\/www.youtube.com\/channel\/UCe007LfgFFnntDgCcqICbPQ"]},{"@type":"Person","@id":"https:\/\/smartcherry.cl\/#\/schema\/person\/604ed44370e96b081064b745ca461407","name":"Beatriz Parra","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2025\/01\/POST-96x96.png","url":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2025\/01\/POST-96x96.png","contentUrl":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2025\/01\/POST-96x96.png","caption":"Beatriz Parra"},"url":"https:\/\/smartcherry.cl\/en\/author\/bparra\/"}]}},"_links":{"self":[{"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/posts\/52655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/users\/273"}],"replies":[{"embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/comments?post=52655"}],"version-history":[{"count":2,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/posts\/52655\/revisions"}],"predecessor-version":[{"id":52660,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/posts\/52655\/revisions\/52660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/media\/52656"}],"wp:attachment":[{"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/media?parent=52655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/categories?post=52655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/tags?post=52655"},{"taxonomy":"category_proveedor","embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/category_proveedor?post=52655"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/pais?post=52655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}