{"id":47563,"date":"2025-07-10T14:50:11","date_gmt":"2025-07-10T18:50:11","guid":{"rendered":"https:\/\/smartcherry.cl\/?p=47563"},"modified":"2025-07-10T14:50:13","modified_gmt":"2025-07-10T18:50:13","slug":"felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones","status":"publish","type":"post","link":"https:\/\/smartcherry.cl\/en\/comercial\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\/","title":{"rendered":"Felipe Massanes: \u201cLos cambios de estrategia de la nueva temporada marcar\u00e1n el futuro de las nuevas plantaciones\u201d"},"content":{"rendered":"<p><strong><em>En conversaci\u00f3n con Smartcherry, el ejecutivo resalt\u00f3 los factores a considerar a la hora de plantar, que van desde densidades de plantaci\u00f3n, sistemas de conducci\u00f3n y la elecci\u00f3n de la variedad a plantar ya sea por su potencial productivo, precocidad o aceptaci\u00f3n de \u00e9sta en el mercado asi\u00e1tico.<\/em><\/strong><\/p>\n\n\n\n<p>Por otro lado fue enf\u00e1tico en se\u00f1alar que es de suma importancia la elecci\u00f3n del proveedor de las plantas, donde se debe tener claridad de los protocolos sanitarios que cuenta dicho vivero y la trazabilidad de los materiales que usa para as\u00ed entregar un buen producto que asegure la inversi\u00f3n del productor.<\/p>\n\n\n\n<p><strong>&#8211; \u00bfCu\u00e1les son los criterios que hoy deben existir para nuevas plantaciones de cereza?<\/strong><br><em>\u00abCreo que es fundamental entender el contexto donde est\u00e1 situada la industria. Hace 15 a\u00f1os el productor pod\u00eda obtener f\u00e1cilmente altos retornos en huertos que ten\u00edan un potencial productivo de 8 \u00f3 10 mil toneladas por hect\u00e1rea, incluso menos y sin importar la zona o semana de cosecha, y el mercado a su vez ten\u00eda mayor tolerancia a las calidades. Hoy, la cantidad de hect\u00e1reas plantadas en el pa\u00eds hace que la elecci\u00f3n o criterios para una nueva plantaci\u00f3n sean varios. Uno de ellos es la semana que queremos cosechar la fruta, potencial productivo de la variedad o incluso resistencia a la lluvia que pueda tener dicha variedad para as\u00ed evitar inversiones adicionales.<\/em><\/p>\n\n\n\n<p><em>El potencial productivo claramente toma fuerza y evitar las semanas con mayor volumen de fruta. En esa l\u00ednea, es clave entender las variedades que hay disponibles en el mercado y cu\u00e1les se pueden adaptar a nuestra zona. Hoy est\u00e1 llegando nueva gen\u00e9tica sumamente atractiva, donde hay variedades que tienen pr\u00e1cticamente todo lo que uno pueda requerir de parte de ella, ll\u00e1mese requerimiento horas fr\u00edo, productividad, fechas de cosecha (ultra tempranas o ultra tard\u00edas), resistencia a partidura, etc.\u00bb.<\/em><\/p>\n\n\n\n<p><strong>&#8211; \u00bfQu\u00e9 factores a tu juicio son claves en la elecci\u00f3n de variedades?<\/strong><br><em>\u00abSiempre es muy atractivo lo precoz. Estar m\u00e1s solo en la industria es m\u00e1s atractivo desde el punto de vista oferta y demanda. Lamentablemente, no todos pueden estar en la parte temprana, ya sea por clima o por disponibilidad de suelo en dichas zonas. Es ah\u00ed donde otros factores toman relevancia, como por ejemplo potenciales productivos, aceptaci\u00f3n de una variedad por las cualidades de sabor y firmeza, o en un extremo variedades que sean cerradas con limitaci\u00f3n de hect\u00e1reas plantadas y controladas por un grupo de exportadoras para as\u00ed controlar el volumen de venta y darle un valor a la marca.<\/em><\/p>\n\n\n\n<p><em>La elecci\u00f3n de la variedad est\u00e1 tomada por un sinn\u00famero de factores, que van a depender de cada productor, pero sin lugar a dudas hoy m\u00e1s que nunca es importante entender la industria, entender el potencial productivo de las zonas e informarse de la gen\u00e9tica disponible que hay en nuestro pa\u00eds en los diferentes viveros\u00bb.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image alignleft size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"849\" height=\"1024\" src=\"https:\/\/smartcherry.cl\/wp-content\/uploads\/2025\/07\/Felipe-Massanes-849x1024.jpeg\" alt=\"\" class=\"wp-image-47565\" style=\"width:386px;height:auto\" srcset=\"https:\/\/smartcherry.cl\/wp-content\/uploads\/2025\/07\/Felipe-Massanes-849x1024.jpeg 849w, https:\/\/smartcherry.cl\/wp-content\/uploads\/2025\/07\/Felipe-Massanes-249x300.jpeg 249w, https:\/\/smartcherry.cl\/wp-content\/uploads\/2025\/07\/Felipe-Massanes-768x927.jpeg 768w, https:\/\/smartcherry.cl\/wp-content\/uploads\/2025\/07\/Felipe-Massanes-10x12.jpeg 10w, https:\/\/smartcherry.cl\/wp-content\/uploads\/2025\/07\/Felipe-Massanes.jpeg 1061w\" sizes=\"(max-width: 849px) 100vw, 849px\" \/><figcaption class=\"wp-element-caption\">Felipe Massanes<\/figcaption><\/figure>\n\n\n\n<p><strong>&#8211; \u00bfHay alguna \u00e9poca del a\u00f1o que sea m\u00e1s propicia que otra para realizar una plantaci\u00f3n de cerezo?<\/strong><br><em>\u00abLa plantaci\u00f3n de la planta barbada debe ser en invierno, idealmente antes de agosto. La idea es que \u00e9sta reciba las \u00faltimas lluvias del invierno, cerrar los bolsones de aire que pudiesen haber quedado en el hoyo de la plantaci\u00f3n y partir la primavera con la planta bien establecida en el huerto. Una mala plantaci\u00f3n, o mal cuidado de ella, genera malos inicios de brotaci\u00f3n y estr\u00e9s en el primer a\u00f1o de crecimiento o incluso mortandad de la planta.&nbsp;<\/em><\/p>\n\n\n\n<p><em>Tambi\u00e9n hay otro producto que muchos viveros ofrecemos, que es una planta en pote, que se entrega en primavera con un brote peque\u00f1o, con la variedad creciendo, y se entrega para que pueda ser plantada a inicios de la primavera, cuando todav\u00eda la temperatura es m\u00e1s fresca y amigable\u00bb.<\/em><\/p>\n\n\n\n<p><strong>&#8211; \u00bfConsideras que la reciente temporada 2024-25 impact\u00f3 en la demanda de nuevas plantaciones de cereza?<\/strong><br><em>\u00abEl a\u00f1o pasado fue una temporada at\u00edpica en la l\u00ednea de tiempo porque si consideramos el a\u00f1o 2024, cuando los productores recibieron la liquidaci\u00f3n, se gener\u00f3 una alta demanda por nuevas plantas para futuros proyectos. El invierno 2024 muchos viveros quebraron stock. Y cuando empezaron a llegar las noticias que la temporada 24-25 no estaba siendo f\u00e1cil y las noticias no eran las esperadas, se fren\u00f3 por completo la solicitud de plantas.<\/em><\/p>\n\n\n\n<p><em>Una vez que llegaron las liquidaciones, la industria analiz\u00f3 la situaci\u00f3n y pudo tomar decisiones en base a ello. Hubo zonas que obtuvieron liquidaciones aceptables y zonas con realidades muy complejas. Efectivamente no est\u00e1 la misma demanda de antes, pero siguen habiendo grandes proyectos, siguen potenci\u00e1ndose zonas tempranas y siguen potenci\u00e1ndose variedades productivas. La diferencia est\u00e1 en que ahora los productores est\u00e1n analizando mejor todos los escenarios para tomar la decisi\u00f3n de plantar.&nbsp;<\/em><\/p>\n\n\n\n<p><em>Esta temporada va a ser determinante para entender cu\u00e1les van a ser las medidas que tomar\u00e1n las exportadoras, las medidas de los productores sobre qu\u00e9 fruta mandar, de qu\u00e9 forma ajustar los costos, c\u00f3mo ser m\u00e1s eficientes. La temporada que se nos avecina sin lugar a dudas marcar\u00e1 un antes y un despu\u00e9s, de seguro habr\u00e1n nuevas exigencias y nuevas estrategias para poder llegar a los resultados esperados. Sin embargo, eso se ver\u00e1 una vez que termine la venta de fruta y tengamos los resultados a inicio del 2026&#8243;.&nbsp;<\/em><\/p>\n\n\n\n<p><strong>&#8211; \u00bfQu\u00e9 otras consideraciones se deben tener en cuenta a la hora de realizar una plantaci\u00f3n de esta fruta?<\/strong><br><em>\u00abEs muy relevante elegir plantas de viveros con buenas pr\u00e1cticas sanitarias y trazabilidad para asegurar la inversi\u00f3n del productor, ya que muchas veces la adquisici\u00f3n de plantas baratas o de origen desconocido, conllevan problemas como enfermedades, o variedades incorrectas que pueden afectar el proyecto a largo plazo y que termine siendo un hoyo sin fondo. Por eso, recomiendo elegir viveros inscritos en la AGV y conocer sus protocolos para garantizar la calidad de las plantas. La planta es la base de un proyecto agr\u00edcola y es la base de la producci\u00f3n, por ello es clave tomarse en serio la elecci\u00f3n y garant\u00eda que nos pueda dar el proveedor de plantas\u00bb.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Con m\u00e1s de 20 a\u00f1os en la industria del viverismo y como productor de cerezas, el Gerente Comercial  y de Producci\u00f3n de Univiveros habl\u00f3 sobre los desaf\u00edos que la reciente temporada del fruto rojo dej\u00f3 desde el punto de vista de los criterios que hoy se deben tener para nuevas plantaciones.<\/p>","protected":false},"author":273,"featured_media":47564,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1717,15,448],"tags":[112,124,4017,4184,4185],"category_proveedor":[],"pais":[],"class_list":["post-47563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevista","category-nuevos-proyectos","category-comercial","tag-cereza","tag-nuevos-proyectos","tag-plantaciones","tag-felipe-massanes","tag-univiveros"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.3 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Felipe Massanes: \u201cLos cambios de estrategia de la nueva temporada marcar\u00e1n el futuro de las nuevas plantaciones\u201d - Smartcherry<\/title>\n<meta name=\"description\" content=\"En conversaci\u00f3n con Smartcherry, el ejecutivo resalt\u00f3 los factores a considerar a la hora de plantar, que van desde densidades de plantaci\u00f3n, sistemas de conducci\u00f3n y la elecci\u00f3n de la variedad a plantar ya sea por su potencial productivo, precocidad o aceptaci\u00f3n de \u00e9sta en el mercado asi\u00e1tico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smartcherry.cl\/en\/comercial\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Felipe Massanes: \u201cLos cambios de estrategia de la nueva temporada marcar\u00e1n el futuro de las nuevas plantaciones\u201d\" \/>\n<meta property=\"og:description\" content=\"En conversaci\u00f3n con Smartcherry, el ejecutivo resalt\u00f3 los factores a considerar a la hora de plantar, que van desde densidades de plantaci\u00f3n, sistemas de conducci\u00f3n y la elecci\u00f3n de la variedad a plantar ya sea por su potencial productivo, precocidad o aceptaci\u00f3n de \u00e9sta en el mercado asi\u00e1tico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smartcherry.cl\/en\/comercial\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Smartcherry\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/SmartCherry.cl\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-10T18:50:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-10T18:50:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smartcherry.cl\/wp-content\/uploads\/2025\/07\/Huerto_nueva-plantacion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Beatriz Parra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SmartCherry_cl\" \/>\n<meta name=\"twitter:site\" content=\"@SmartCherry_cl\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Beatriz Parra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/comercial\\\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/comercial\\\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\\\/\"},\"author\":{\"name\":\"Beatriz Parra\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#\\\/schema\\\/person\\\/604ed44370e96b081064b745ca461407\"},\"headline\":\"Felipe Massanes: \u201cLos cambios de estrategia de la nueva temporada marcar\u00e1n el futuro de las nuevas plantaciones\u201d\",\"datePublished\":\"2025-07-10T18:50:11+00:00\",\"dateModified\":\"2025-07-10T18:50:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/comercial\\\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\\\/\"},\"wordCount\":1091,\"publisher\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/comercial\\\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Huerto_nueva-plantacion.jpg\",\"keywords\":[\"cereza\",\"nuevos proyectos\",\"Plantaciones\",\"Felipe Massanes\",\"Univiveros\"],\"articleSection\":[\"Entrevista\",\"Nuevos proyectos\",\"Comercial\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/comercial\\\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\\\/\",\"url\":\"https:\\\/\\\/smartcherry.cl\\\/comercial\\\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\\\/\",\"name\":\"Felipe Massanes: \u201cLos cambios de estrategia de la nueva temporada marcar\u00e1n el futuro de las nuevas plantaciones\u201d - Smartcherry\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/comercial\\\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/comercial\\\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Huerto_nueva-plantacion.jpg\",\"datePublished\":\"2025-07-10T18:50:11+00:00\",\"dateModified\":\"2025-07-10T18:50:13+00:00\",\"description\":\"En conversaci\u00f3n con Smartcherry, el ejecutivo resalt\u00f3 los factores a considerar a la hora de plantar, que van desde densidades de plantaci\u00f3n, sistemas de conducci\u00f3n y la elecci\u00f3n de la variedad a plantar ya sea por su potencial productivo, precocidad o aceptaci\u00f3n de \u00e9sta en el mercado asi\u00e1tico.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/comercial\\\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smartcherry.cl\\\/comercial\\\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/comercial\\\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Huerto_nueva-plantacion.jpg\",\"contentUrl\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Huerto_nueva-plantacion.jpg\",\"width\":1400,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/comercial\\\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smartcherry.cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comercial\",\"item\":\"https:\\\/\\\/smartcherry.cl\\\/category\\\/comercial\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Felipe Massanes: \u201cLos cambios de estrategia de la nueva temporada marcar\u00e1n el futuro de las nuevas plantaciones\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#website\",\"url\":\"https:\\\/\\\/smartcherry.cl\\\/\",\"name\":\"Smartcherry\",\"description\":\"Sitio de Smartcherry\",\"publisher\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smartcherry.cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#organization\",\"name\":\"SmartCherry\",\"url\":\"https:\\\/\\\/smartcherry.cl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo_smartcherry.png\",\"contentUrl\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo_smartcherry.png\",\"width\":411,\"height\":84,\"caption\":\"SmartCherry\"},\"image\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/SmartCherry.cl\\\/\",\"https:\\\/\\\/x.com\\\/SmartCherry_cl\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/smartcherry\\\/\",\"https:\\\/\\\/www.instagram.com\\\/smartcherry_cl\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCe007LfgFFnntDgCcqICbPQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#\\\/schema\\\/person\\\/604ed44370e96b081064b745ca461407\",\"name\":\"Beatriz Parra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/POST-96x96.png\",\"url\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/POST-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/POST-96x96.png\",\"caption\":\"Beatriz Parra\"},\"url\":\"https:\\\/\\\/smartcherry.cl\\\/en\\\/author\\\/bparra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Felipe Massanes: \u201cLos cambios de estrategia de la nueva temporada marcar\u00e1n el futuro de las nuevas plantaciones\u201d - Smartcherry","description":"En conversaci\u00f3n con Smartcherry, el ejecutivo resalt\u00f3 los factores a considerar a la hora de plantar, que van desde densidades de plantaci\u00f3n, sistemas de conducci\u00f3n y la elecci\u00f3n de la variedad a plantar ya sea por su potencial productivo, precocidad o aceptaci\u00f3n de \u00e9sta en el mercado asi\u00e1tico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smartcherry.cl\/en\/comercial\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\/","og_locale":"en_US","og_type":"article","og_title":"Felipe Massanes: \u201cLos cambios de estrategia de la nueva temporada marcar\u00e1n el futuro de las nuevas plantaciones\u201d","og_description":"En conversaci\u00f3n con Smartcherry, el ejecutivo resalt\u00f3 los factores a considerar a la hora de plantar, que van desde densidades de plantaci\u00f3n, sistemas de conducci\u00f3n y la elecci\u00f3n de la variedad a plantar ya sea por su potencial productivo, precocidad o aceptaci\u00f3n de \u00e9sta en el mercado asi\u00e1tico.","og_url":"https:\/\/smartcherry.cl\/en\/comercial\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\/","og_site_name":"Smartcherry","article_publisher":"https:\/\/web.facebook.com\/SmartCherry.cl\/","article_published_time":"2025-07-10T18:50:11+00:00","article_modified_time":"2025-07-10T18:50:13+00:00","og_image":[{"width":1400,"height":800,"url":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2025\/07\/Huerto_nueva-plantacion.jpg","type":"image\/jpeg"}],"author":"Beatriz Parra","twitter_card":"summary_large_image","twitter_creator":"@SmartCherry_cl","twitter_site":"@SmartCherry_cl","twitter_misc":{"Written by":"Beatriz Parra","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smartcherry.cl\/comercial\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\/#article","isPartOf":{"@id":"https:\/\/smartcherry.cl\/comercial\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\/"},"author":{"name":"Beatriz Parra","@id":"https:\/\/smartcherry.cl\/#\/schema\/person\/604ed44370e96b081064b745ca461407"},"headline":"Felipe Massanes: \u201cLos cambios de estrategia de la nueva temporada marcar\u00e1n el futuro de las nuevas plantaciones\u201d","datePublished":"2025-07-10T18:50:11+00:00","dateModified":"2025-07-10T18:50:13+00:00","mainEntityOfPage":{"@id":"https:\/\/smartcherry.cl\/comercial\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\/"},"wordCount":1091,"publisher":{"@id":"https:\/\/smartcherry.cl\/#organization"},"image":{"@id":"https:\/\/smartcherry.cl\/comercial\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2025\/07\/Huerto_nueva-plantacion.jpg","keywords":["cereza","nuevos proyectos","Plantaciones","Felipe Massanes","Univiveros"],"articleSection":["Entrevista","Nuevos proyectos","Comercial"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/smartcherry.cl\/comercial\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\/","url":"https:\/\/smartcherry.cl\/comercial\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\/","name":"Felipe Massanes: \u201cLos cambios de estrategia de la nueva temporada marcar\u00e1n el futuro de las nuevas plantaciones\u201d - Smartcherry","isPartOf":{"@id":"https:\/\/smartcherry.cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smartcherry.cl\/comercial\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\/#primaryimage"},"image":{"@id":"https:\/\/smartcherry.cl\/comercial\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2025\/07\/Huerto_nueva-plantacion.jpg","datePublished":"2025-07-10T18:50:11+00:00","dateModified":"2025-07-10T18:50:13+00:00","description":"En conversaci\u00f3n con Smartcherry, el ejecutivo resalt\u00f3 los factores a considerar a la hora de plantar, que van desde densidades de plantaci\u00f3n, sistemas de conducci\u00f3n y la elecci\u00f3n de la variedad a plantar ya sea por su potencial productivo, precocidad o aceptaci\u00f3n de \u00e9sta en el mercado asi\u00e1tico.","breadcrumb":{"@id":"https:\/\/smartcherry.cl\/comercial\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smartcherry.cl\/comercial\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/smartcherry.cl\/comercial\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\/#primaryimage","url":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2025\/07\/Huerto_nueva-plantacion.jpg","contentUrl":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2025\/07\/Huerto_nueva-plantacion.jpg","width":1400,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/smartcherry.cl\/comercial\/felipe-massanes-los-cambios-de-estrategia-de-la-nueva-temporada-marcaran-el-futuro-de-las-nuevas-plantaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smartcherry.cl\/"},{"@type":"ListItem","position":2,"name":"Comercial","item":"https:\/\/smartcherry.cl\/category\/comercial\/"},{"@type":"ListItem","position":3,"name":"Felipe Massanes: \u201cLos cambios de estrategia de la nueva temporada marcar\u00e1n el futuro de las nuevas plantaciones\u201d"}]},{"@type":"WebSite","@id":"https:\/\/smartcherry.cl\/#website","url":"https:\/\/smartcherry.cl\/","name":"Smartcherry","description":"Smartcherry Site","publisher":{"@id":"https:\/\/smartcherry.cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smartcherry.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/smartcherry.cl\/#organization","name":"SmartCherry","url":"https:\/\/smartcherry.cl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/smartcherry.cl\/#\/schema\/logo\/image\/","url":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2022\/02\/logo_smartcherry.png","contentUrl":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2022\/02\/logo_smartcherry.png","width":411,"height":84,"caption":"SmartCherry"},"image":{"@id":"https:\/\/smartcherry.cl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/SmartCherry.cl\/","https:\/\/x.com\/SmartCherry_cl","https:\/\/www.linkedin.com\/company\/smartcherry\/","https:\/\/www.instagram.com\/smartcherry_cl\/","https:\/\/www.youtube.com\/channel\/UCe007LfgFFnntDgCcqICbPQ"]},{"@type":"Person","@id":"https:\/\/smartcherry.cl\/#\/schema\/person\/604ed44370e96b081064b745ca461407","name":"Beatriz Parra","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2025\/01\/POST-96x96.png","url":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2025\/01\/POST-96x96.png","contentUrl":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2025\/01\/POST-96x96.png","caption":"Beatriz Parra"},"url":"https:\/\/smartcherry.cl\/en\/author\/bparra\/"}]}},"_links":{"self":[{"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/posts\/47563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/users\/273"}],"replies":[{"embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/comments?post=47563"}],"version-history":[{"count":2,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/posts\/47563\/revisions"}],"predecessor-version":[{"id":47567,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/posts\/47563\/revisions\/47567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/media\/47564"}],"wp:attachment":[{"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/media?parent=47563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/categories?post=47563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/tags?post=47563"},{"taxonomy":"category_proveedor","embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/category_proveedor?post=47563"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/pais?post=47563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}