{"id":41126,"date":"2024-11-06T09:24:38","date_gmt":"2024-11-06T13:24:38","guid":{"rendered":"https:\/\/smartcherry.cl\/?p=41126"},"modified":"2024-11-06T09:24:40","modified_gmt":"2024-11-06T13:24:40","slug":"la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais","status":"publish","type":"post","link":"https:\/\/smartcherry.cl\/en\/noticias\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\/","title":{"rendered":"La pr\u00f3xima semana comienza  la cosecha de cerezas en la zona central del pa\u00eds"},"content":{"rendered":"<p class=\"wp-block-paragraph\">La pr\u00f3xima semana comenzar\u00e1 oficialmente la cosecha de cerezas de la temporada 2024-2025 en la zona central de Chile, marcando el inicio de uno de los periodos m\u00e1s esperados en el sector frut\u00edcola. Las regiones de O&#8217;Higgins y Maule, que representan m\u00e1s del 80% de las plantaciones de cerezas en el pa\u00eds, liderar\u00e1n esta primera fase con la recolecci\u00f3n de las variedades m\u00e1s tempranas, aprovechando las condiciones clim\u00e1ticas favorables, aunque inestables,  que prometen una cosecha de alta calidad y excelente color.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta temporada, los productores de la zona tienen grandes expectativas y destacan la relevancia de la proyecci\u00f3n de la oferta exportadora chilena. Luis Contreras, productor de la regi\u00f3n de O&#8217;Higgins, expres\u00f3 su optimismo: <em>\u201cNos hemos preparado durante todo el a\u00f1o para lograr una cosecha exitosa, ajust\u00e1ndonos a los m\u00e1s altos est\u00e1ndares de calidad y aprovechando las condiciones favorables que hemos tenido. La demanda internacional por nuestra cereza est\u00e1 en alza, y estamos listos para competir en los mercados m\u00e1s exigentes.\u201d<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Reinaldo Huentupil, encargado del huerto Longo, ubicado en la comuna de Rauco, regi\u00f3n del Maule, a\u00f1adi\u00f3: <em>\u00abPartiremos cosechando aproximadamente el 25 de noviembre la variedad Santina; est\u00e1 temporada hay un 15 por ciento m\u00e1s de fruta respecto de la temporada pasada. Estamos confiados en que este a\u00f1o tendremos un producto excelente\u00bb.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La temporada de cerezas en Chile es una de las m\u00e1s din\u00e1micas dentro de las exportaciones agr\u00edcolas nacionales, y el inicio de la cosecha en estas zonas representa un gran impulso para la oferta exportadora del pa\u00eds. Las variedades tempranas ser\u00e1n las primeras en ser recolectadas y enviadas a los mercados internacionales, dando inicio a una campa\u00f1a que promete satisfacer la alta demanda de este fruto en los principales destinos de exportaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el comienzo de la cosecha en O&#8217;Higgins y Maule, Chile se alista para lo que se proyecta como una exitosa temporada de cerezas, con una estimaci\u00f3n de 131 millones de cajas de 5 kilos, consolid\u00e1ndose como l\u00edder mundial en la exportaci\u00f3n de esta preciada fruta.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a1Parte la nueva temporada!<\/p>","protected":false},"author":239,"featured_media":41151,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[35],"tags":[274,3585],"category_proveedor":[],"pais":[],"class_list":["post-41126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-cosecha","tag-temporada-2024-2025"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La pr\u00f3xima semana comienza la cosecha de cerezas en la zona central del pa\u00eds - Smartcherry<\/title>\n<meta name=\"description\" content=\"\u00bfCu\u00e1ndo parte la cosecha de cerezas en la zona central del pa\u00eds? Revisa la nota con todos los detalles del inicio oficial de la cosecha.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smartcherry.cl\/en\/noticias\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La pr\u00f3xima semana comienza la cosecha de cerezas en la zona central del pa\u00eds\" \/>\n<meta property=\"og:description\" content=\"\u00bfCu\u00e1ndo parte la cosecha de cerezas en la zona central del pa\u00eds? Revisa la nota con todos los detalles del inicio oficial de la cosecha.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smartcherry.cl\/en\/noticias\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\/\" \/>\n<meta property=\"og:site_name\" content=\"Smartcherry\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/SmartCherry.cl\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-06T13:24:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-06T13:24:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smartcherry.cl\/wp-content\/uploads\/2024\/11\/portada-1400x800-26-1024x585.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"585\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Andrea Garrido\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SmartCherry_cl\" \/>\n<meta name=\"twitter:site\" content=\"@SmartCherry_cl\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Garrido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\\\/\"},\"author\":{\"name\":\"Andrea Garrido\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#\\\/schema\\\/person\\\/8af97e16113dce4b990e1e4cec380025\"},\"headline\":\"La pr\u00f3xima semana comienza la cosecha de cerezas en la zona central del pa\u00eds\",\"datePublished\":\"2024-11-06T13:24:38+00:00\",\"dateModified\":\"2024-11-06T13:24:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\\\/\"},\"wordCount\":378,\"publisher\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/portada-1400x800-26.png\",\"keywords\":[\"cosecha\",\"temporada 2024-2025\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\\\/\",\"url\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\\\/\",\"name\":\"La pr\u00f3xima semana comienza la cosecha de cerezas en la zona central del pa\u00eds - Smartcherry\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/portada-1400x800-26.png\",\"datePublished\":\"2024-11-06T13:24:38+00:00\",\"dateModified\":\"2024-11-06T13:24:40+00:00\",\"description\":\"\u00bfCu\u00e1ndo parte la cosecha de cerezas en la zona central del pa\u00eds? Revisa la nota con todos los detalles del inicio oficial de la cosecha.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/portada-1400x800-26.png\",\"contentUrl\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/portada-1400x800-26.png\",\"width\":1400,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/noticias\\\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smartcherry.cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/smartcherry.cl\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La pr\u00f3xima semana comienza la cosecha de cerezas en la zona central del pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#website\",\"url\":\"https:\\\/\\\/smartcherry.cl\\\/\",\"name\":\"Smartcherry\",\"description\":\"Sitio de Smartcherry\",\"publisher\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smartcherry.cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#organization\",\"name\":\"SmartCherry\",\"url\":\"https:\\\/\\\/smartcherry.cl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo_smartcherry.png\",\"contentUrl\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo_smartcherry.png\",\"width\":411,\"height\":84,\"caption\":\"SmartCherry\"},\"image\":{\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/SmartCherry.cl\\\/\",\"https:\\\/\\\/x.com\\\/SmartCherry_cl\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/smartcherry\\\/\",\"https:\\\/\\\/www.instagram.com\\\/smartcherry_cl\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCe007LfgFFnntDgCcqICbPQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/#\\\/schema\\\/person\\\/8af97e16113dce4b990e1e4cec380025\",\"name\":\"Andrea Garrido\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Andrea-Garrido-150x150.png\",\"url\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Andrea-Garrido-150x150.png\",\"contentUrl\":\"https:\\\/\\\/smartcherry.cl\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Andrea-Garrido-150x150.png\",\"caption\":\"Andrea Garrido\"},\"url\":\"https:\\\/\\\/smartcherry.cl\\\/en\\\/author\\\/agarrido\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La pr\u00f3xima semana comienza la cosecha de cerezas en la zona central del pa\u00eds - Smartcherry","description":"\u00bfCu\u00e1ndo parte la cosecha de cerezas en la zona central del pa\u00eds? Revisa la nota con todos los detalles del inicio oficial de la cosecha.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smartcherry.cl\/en\/noticias\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\/","og_locale":"en_US","og_type":"article","og_title":"La pr\u00f3xima semana comienza la cosecha de cerezas en la zona central del pa\u00eds","og_description":"\u00bfCu\u00e1ndo parte la cosecha de cerezas en la zona central del pa\u00eds? Revisa la nota con todos los detalles del inicio oficial de la cosecha.","og_url":"https:\/\/smartcherry.cl\/en\/noticias\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\/","og_site_name":"Smartcherry","article_publisher":"https:\/\/web.facebook.com\/SmartCherry.cl\/","article_published_time":"2024-11-06T13:24:38+00:00","article_modified_time":"2024-11-06T13:24:40+00:00","og_image":[{"width":1024,"height":585,"url":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2024\/11\/portada-1400x800-26-1024x585.png","type":"image\/png"}],"author":"Andrea Garrido","twitter_card":"summary_large_image","twitter_creator":"@SmartCherry_cl","twitter_site":"@SmartCherry_cl","twitter_misc":{"Written by":"Andrea Garrido","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smartcherry.cl\/noticias\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\/#article","isPartOf":{"@id":"https:\/\/smartcherry.cl\/noticias\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\/"},"author":{"name":"Andrea Garrido","@id":"https:\/\/smartcherry.cl\/#\/schema\/person\/8af97e16113dce4b990e1e4cec380025"},"headline":"La pr\u00f3xima semana comienza la cosecha de cerezas en la zona central del pa\u00eds","datePublished":"2024-11-06T13:24:38+00:00","dateModified":"2024-11-06T13:24:40+00:00","mainEntityOfPage":{"@id":"https:\/\/smartcherry.cl\/noticias\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\/"},"wordCount":378,"publisher":{"@id":"https:\/\/smartcherry.cl\/#organization"},"image":{"@id":"https:\/\/smartcherry.cl\/noticias\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2024\/11\/portada-1400x800-26.png","keywords":["cosecha","temporada 2024-2025"],"articleSection":["Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/smartcherry.cl\/noticias\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\/","url":"https:\/\/smartcherry.cl\/noticias\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\/","name":"La pr\u00f3xima semana comienza la cosecha de cerezas en la zona central del pa\u00eds - Smartcherry","isPartOf":{"@id":"https:\/\/smartcherry.cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smartcherry.cl\/noticias\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\/#primaryimage"},"image":{"@id":"https:\/\/smartcherry.cl\/noticias\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2024\/11\/portada-1400x800-26.png","datePublished":"2024-11-06T13:24:38+00:00","dateModified":"2024-11-06T13:24:40+00:00","description":"\u00bfCu\u00e1ndo parte la cosecha de cerezas en la zona central del pa\u00eds? Revisa la nota con todos los detalles del inicio oficial de la cosecha.","breadcrumb":{"@id":"https:\/\/smartcherry.cl\/noticias\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smartcherry.cl\/noticias\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/smartcherry.cl\/noticias\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\/#primaryimage","url":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2024\/11\/portada-1400x800-26.png","contentUrl":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2024\/11\/portada-1400x800-26.png","width":1400,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/smartcherry.cl\/noticias\/la-proxima-semana-comienza-la-cosecha-de-cerezas-en-la-zona-central-del-pais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smartcherry.cl\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/smartcherry.cl\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"La pr\u00f3xima semana comienza la cosecha de cerezas en la zona central del pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/smartcherry.cl\/#website","url":"https:\/\/smartcherry.cl\/","name":"Smartcherry","description":"Smartcherry Site","publisher":{"@id":"https:\/\/smartcherry.cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smartcherry.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/smartcherry.cl\/#organization","name":"SmartCherry","url":"https:\/\/smartcherry.cl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/smartcherry.cl\/#\/schema\/logo\/image\/","url":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2022\/02\/logo_smartcherry.png","contentUrl":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2022\/02\/logo_smartcherry.png","width":411,"height":84,"caption":"SmartCherry"},"image":{"@id":"https:\/\/smartcherry.cl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/SmartCherry.cl\/","https:\/\/x.com\/SmartCherry_cl","https:\/\/www.linkedin.com\/company\/smartcherry\/","https:\/\/www.instagram.com\/smartcherry_cl\/","https:\/\/www.youtube.com\/channel\/UCe007LfgFFnntDgCcqICbPQ"]},{"@type":"Person","@id":"https:\/\/smartcherry.cl\/#\/schema\/person\/8af97e16113dce4b990e1e4cec380025","name":"Andrea Garrido","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2022\/03\/Andrea-Garrido-150x150.png","url":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2022\/03\/Andrea-Garrido-150x150.png","contentUrl":"https:\/\/smartcherry.cl\/wp-content\/uploads\/2022\/03\/Andrea-Garrido-150x150.png","caption":"Andrea Garrido"},"url":"https:\/\/smartcherry.cl\/en\/author\/agarrido\/"}]}},"_links":{"self":[{"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/posts\/41126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/users\/239"}],"replies":[{"embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/comments?post=41126"}],"version-history":[{"count":2,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/posts\/41126\/revisions"}],"predecessor-version":[{"id":41152,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/posts\/41126\/revisions\/41152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/media\/41151"}],"wp:attachment":[{"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/media?parent=41126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/categories?post=41126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/tags?post=41126"},{"taxonomy":"category_proveedor","embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/category_proveedor?post=41126"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/smartcherry.cl\/en\/wp-json\/wp\/v2\/pais?post=41126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}